{"id":266,"date":"2016-05-17T08:46:36","date_gmt":"2016-05-17T08:46:36","guid":{"rendered":"http:\/\/downcadiz.com\/?p=266"},"modified":"2018-03-22T08:31:47","modified_gmt":"2018-03-22T08:31:47","slug":"practicas-en-la-cafeteria-de-ciencias-del-trabajo","status":"publish","type":"post","link":"http:\/\/downcadiz.com\/category\/blog\/practicas-en-la-cafeteria-de-ciencias-del-trabajo\/","title":{"rendered":"Pr\u00e1cticas en la Cafeter\u00eda de Ciencias del Trabajo"},"content":{"rendered":"<h6><a href=\"http:\/\/downcadiz.com\/wp-content\/uploads\/2016\/05\/sindromes-down-trabajando-620x349.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-267\" src=\"http:\/\/downcadiz.com\/wp-content\/uploads\/2016\/05\/sindromes-down-trabajando-620x349-300x169.jpg\" alt=\"sindromes-down-trabajando--620x349\" width=\"300\" height=\"169\" srcset=\"http:\/\/downcadiz.com\/wp-content\/uploads\/2016\/05\/sindromes-down-trabajando-620x349-300x169.jpg 300w, http:\/\/downcadiz.com\/wp-content\/uploads\/2016\/05\/sindromes-down-trabajando-620x349.jpg 620w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br \/>\nF<\/a>oto publicada en www.lavozdigital.es<\/h6>\n<p>Desde el pasado 11 de mayo del 2016, la cafeter\u00eda de Ciencias del Trabajo se convierte en el primer establecimiento de hosteler\u00eda de C\u00e1diz con trabajadores con S\u00edndrome de Down.<\/p>\n<p>Tras realizar un curso de Pinche de Cocina impartido por Down C\u00e1diz en colaboraci\u00f3n con FSC Inserta (Fundaci\u00f3n ONCE) y otro de Manipulador de alimentos nuestros alumnos Isa Y Jes\u00fas se han colocado su uniforme para comenzar sus pr\u00e1cticas laborales en el mundo de la hosteler\u00eda.<\/p>\n<p>Enlace de la noticia publicada en el peri\u00f3dico LA VOZ DE C\u00c1DIZ:<\/p>\n<p><a href=\"http:\/\/www.lavozdigital.es\/cadiz\/lvdi-ciencias-trabajo-estrena-catedra-conciencia-laboral-201605151223_noticia.html\">http:\/\/www.lavozdigital.es\/cadiz\/lvdi-ciencias-trabajo-estrena-catedra-conciencia-laboral-201605151223_noticia.html<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foto publicada en www.lavozdigital.es Desde el pasado 11 de mayo del 2016, la cafeter\u00eda de Ciencias del Trabajo se convierte en el primer establecimiento de hosteler\u00eda de C\u00e1diz con trabajadores con S\u00edndrome de Down. Tras realizar un curso de Pinche de Cocina impartido por Down C\u00e1diz en colaboraci\u00f3n con FSC Inserta (Fundaci\u00f3n ONCE) y otro &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/downcadiz.com\/category\/blog\/practicas-en-la-cafeteria-de-ciencias-del-trabajo\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abPr\u00e1cticas en la Cafeter\u00eda de Ciencias del Trabajo\u00bb<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[15,13,14],"_links":{"self":[{"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/posts\/266"}],"collection":[{"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":0,"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"wp:attachment":[{"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/downcadiz.com\/category\/blog\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}